{"id":22,"count":6,"description":"","link":"https:\/\/documents.galileispa.com\/en\/kind\/giano-70-maxi\/","name":"Giano 70 Maxi","slug":"giano-70-maxi","taxonomy":"kind","parent":3,"meta":[],"_links":{"self":[{"href":"https:\/\/documents.galileispa.com\/en\/wp-json\/wp\/v2\/kind\/22"}],"collection":[{"href":"https:\/\/documents.galileispa.com\/en\/wp-json\/wp\/v2\/kind"}],"about":[{"href":"https:\/\/documents.galileispa.com\/en\/wp-json\/wp\/v2\/taxonomies\/kind"}],"up":[{"embeddable":true,"href":"https:\/\/documents.galileispa.com\/en\/wp-json\/wp\/v2\/kind\/3"}],"wp:post_type":[{"href":"https:\/\/documents.galileispa.com\/en\/wp-json\/wp\/v2\/file?kind=22"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}