{"id":33,"count":6,"description":"","link":"https:\/\/documents.galileispa.com\/en\/kind\/gemini-120-d\/","name":"Gemini 120 D","slug":"gemini-120-d","taxonomy":"kind","parent":4,"meta":[],"_links":{"self":[{"href":"https:\/\/documents.galileispa.com\/en\/wp-json\/wp\/v2\/kind\/33"}],"collection":[{"href":"https:\/\/documents.galileispa.com\/en\/wp-json\/wp\/v2\/kind"}],"about":[{"href":"https:\/\/documents.galileispa.com\/en\/wp-json\/wp\/v2\/taxonomies\/kind"}],"up":[{"embeddable":true,"href":"https:\/\/documents.galileispa.com\/en\/wp-json\/wp\/v2\/kind\/4"}],"wp:post_type":[{"href":"https:\/\/documents.galileispa.com\/en\/wp-json\/wp\/v2\/file?kind=33"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}