{"id":5,"count":6,"description":"","link":"https:\/\/documents.galileispa.com\/en\/kind\/norma-90\/","name":"Norma 90","slug":"norma-90","taxonomy":"kind","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/documents.galileispa.com\/en\/wp-json\/wp\/v2\/kind\/5"}],"collection":[{"href":"https:\/\/documents.galileispa.com\/en\/wp-json\/wp\/v2\/kind"}],"about":[{"href":"https:\/\/documents.galileispa.com\/en\/wp-json\/wp\/v2\/taxonomies\/kind"}],"wp:post_type":[{"href":"https:\/\/documents.galileispa.com\/en\/wp-json\/wp\/v2\/file?kind=5"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}